{"id":30241,"date":"2024-01-26T11:43:14","date_gmt":"2024-02-01T14:02:04","guid":{"rendered":"https:\/\/naturalpoland.com\/produkty\/sin%20categor\u00eda\/extracto-de-bacopa-de-hoja-pequena\/"},"modified":"2024-04-29T14:52:53","modified_gmt":"2024-04-29T12:52:53","slug":"extracto-de-bacopa-de-hoja-pequena","status":"publish","type":"product","link":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/","title":{"rendered":"Extracto de bacopa de hoja peque\u00f1a"},"content":{"rendered":"<p>El contenido en bacopasida del extracto de bacopa es superior al 20%, lo que indica su alta calidad. Este extracto se presenta en forma de polvo fino, de color marr\u00f3n amarillento y olor y sabor caracter\u00edsticos.<\/p>\n<p>Sus principales usos incluyen la mejora de la memoria, la concentraci\u00f3n y el apoyo a la reducci\u00f3n del estr\u00e9s y la tensi\u00f3n. Tambi\u00e9n act\u00faa como adapt\u00f3geno, ayudando al organismo a hacer frente a los efectos del estr\u00e9s f\u00edsico y mental.<\/p>\n<p>El producto se obtuvo a partir de la planta entera utilizando etanol y agua como disolventes, sin a\u00f1adir OMG ni contaminantes como metales pesados o pesticidas. Su uso es seguro, seg\u00fan las pruebas microbiol\u00f3gicas y toxicol\u00f3gicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Extracto de Bacopa Monnieri<\/strong> (<em><br \/>\n  <strong>Bacopa Monnieri<\/strong><br \/>\n<\/em>) es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional, valorada por sus propiedades para mejorar la funci\u00f3n cognitiva y favorecer la salud mental en general.<\/p>\n","protected":false},"featured_media":29940,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1079],"product_tag":[],"class_list":["post-30241","product","type-product","status-publish","has-post-thumbnail","product_cat-extractos-de-plantas","pa_certyfikaty-certificacion-kosher","pa_certyfikaty-halal-es","pa_czesc-rosliny-planta-entera","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extracto de bacopa de hoja peque\u00f1a - Distribuidor mayorista<\/title>\n<meta name=\"description\" content=\"El extracto de Bacopa Monnieri es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extracto de bacopa de hoja peque\u00f1a - Distribuidor mayorista\" \/>\n<meta property=\"og:description\" content=\"El extracto de Bacopa Monnieri es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/\" \/>\n<meta property=\"og:site_name\" content=\"NATURAL POLAND - Distribuidor Mayorista de Materias Primas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/naturalpoland.b2b\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-29T12:52:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturalpoland.com\/wp-content\/uploads\/bacopa_monnieri_extract.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"614\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/\",\"url\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/\",\"name\":\"Extracto de bacopa de hoja peque\u00f1a - Distribuidor mayorista\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturalpoland.com\\\/wp-content\\\/uploads\\\/bacopa_monnieri_extract.webp\",\"datePublished\":\"2024-02-01T14:02:04+00:00\",\"dateModified\":\"2024-04-29T12:52:53+00:00\",\"description\":\"El extracto de Bacopa Monnieri es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naturalpoland.com\\\/wp-content\\\/uploads\\\/bacopa_monnieri_extract.webp\",\"contentUrl\":\"https:\\\/\\\/naturalpoland.com\\\/wp-content\\\/uploads\\\/bacopa_monnieri_extract.webp\",\"width\":614,\"height\":614,\"caption\":\"ekstrakt z bakopy drobnolistnej\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/extractos-de-plantas\\\/extracto-de-bacopa-de-hoja-pequena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Extracto de bacopa de hoja peque\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/\",\"name\":\"NATURAL POLAND - Distribuidor Mayorista de Materias Primas\",\"description\":\"Surowce dla przemys\u0142u spo\u017cywczego, kosmetycznego i farmaceutycznego\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/#organization\",\"name\":\"Natural Poland\",\"url\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naturalpoland.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/natural-poland-icon.png\",\"contentUrl\":\"https:\\\/\\\/naturalpoland.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/natural-poland-icon.png\",\"width\":512,\"height\":512,\"caption\":\"Natural Poland\"},\"image\":{\"@id\":\"https:\\\/\\\/naturalpoland.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/naturalpoland.b2b\",\"https:\\\/\\\/pl.linkedin.com\\\/company\\\/natural-poland\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgeGGkvOMahZo-xu_MSEWxg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extracto de bacopa de hoja peque\u00f1a - Distribuidor mayorista","description":"El extracto de Bacopa Monnieri es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/","og_locale":"es_ES","og_type":"article","og_title":"Extracto de bacopa de hoja peque\u00f1a - Distribuidor mayorista","og_description":"El extracto de Bacopa Monnieri es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional.","og_url":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/","og_site_name":"NATURAL POLAND - Distribuidor Mayorista de Materias Primas","article_publisher":"https:\/\/www.facebook.com\/naturalpoland.b2b","article_modified_time":"2024-04-29T12:52:53+00:00","og_image":[{"width":614,"height":614,"url":"https:\/\/naturalpoland.com\/wp-content\/uploads\/bacopa_monnieri_extract.webp","type":"image\/webp"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/","url":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/","name":"Extracto de bacopa de hoja peque\u00f1a - Distribuidor mayorista","isPartOf":{"@id":"https:\/\/naturalpoland.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/#primaryimage"},"image":{"@id":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/#primaryimage"},"thumbnailUrl":"https:\/\/naturalpoland.com\/wp-content\/uploads\/bacopa_monnieri_extract.webp","datePublished":"2024-02-01T14:02:04+00:00","dateModified":"2024-04-29T12:52:53+00:00","description":"El extracto de Bacopa Monnieri es una conocida materia prima utilizada en la medicina ayurv\u00e9dica tradicional.","breadcrumb":{"@id":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/#primaryimage","url":"https:\/\/naturalpoland.com\/wp-content\/uploads\/bacopa_monnieri_extract.webp","contentUrl":"https:\/\/naturalpoland.com\/wp-content\/uploads\/bacopa_monnieri_extract.webp","width":614,"height":614,"caption":"ekstrakt z bakopy drobnolistnej"},{"@type":"BreadcrumbList","@id":"https:\/\/naturalpoland.com\/es\/productos\/extractos-de-plantas\/extracto-de-bacopa-de-hoja-pequena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/naturalpoland.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/naturalpoland.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Extracto de bacopa de hoja peque\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/naturalpoland.com\/es\/#website","url":"https:\/\/naturalpoland.com\/es\/","name":"NATURAL POLAND - Distribuidor Mayorista de Materias Primas","description":"Surowce dla przemys\u0142u spo\u017cywczego, kosmetycznego i farmaceutycznego","publisher":{"@id":"https:\/\/naturalpoland.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturalpoland.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/naturalpoland.com\/es\/#organization","name":"Natural Poland","url":"https:\/\/naturalpoland.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/naturalpoland.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/naturalpoland.com\/wp-content\/uploads\/2021\/05\/natural-poland-icon.png","contentUrl":"https:\/\/naturalpoland.com\/wp-content\/uploads\/2021\/05\/natural-poland-icon.png","width":512,"height":512,"caption":"Natural Poland"},"image":{"@id":"https:\/\/naturalpoland.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/naturalpoland.b2b","https:\/\/pl.linkedin.com\/company\/natural-poland","https:\/\/www.youtube.com\/channel\/UCgeGGkvOMahZo-xu_MSEWxg"]}]}},"_links":{"self":[{"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/product\/30241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/media\/29940"}],"wp:attachment":[{"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/media?parent=30241"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/product_brand?post=30241"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/product_cat?post=30241"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/naturalpoland.com\/es\/wp-json\/wp\/v2\/product_tag?post=30241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}